{"id":73,"date":"2013-08-26T17:45:35","date_gmt":"2013-08-26T15:45:35","guid":{"rendered":"http:\/\/www.mobile-apfelquetsche.de\/?page_id=73"},"modified":"2013-09-04T16:00:34","modified_gmt":"2013-09-04T14:00:34","slug":"agb","status":"publish","type":"page","link":"https:\/\/www.mobile-apfelquetsche.de\/idee-apfelquetsche\/agb\/","title":{"rendered":"Allgemeine Gesch\u00e4ftsbedingungen"},"content":{"rendered":"<p><img loading=\"lazy\" src=\"http:\/\/www.mobile-apfelquetsche.de\/wp-content\/uploads\/2013\/08\/obstpresse-2.jpg\" alt=\"obstpresse\" width=\"309\" height=\"515\" class=\"alignright size-full wp-image-153\" srcset=\"https:\/\/www.mobile-apfelquetsche.de\/wp-content\/uploads\/2013\/08\/obstpresse-2.jpg 309w, https:\/\/www.mobile-apfelquetsche.de\/wp-content\/uploads\/2013\/08\/obstpresse-2-180x300.jpg 180w\" sizes=\"(max-width: 309px) 100vw, 309px\" \/><\/p>\n<p>Wir werden vorrangig im deutschen Raum arbeiten, falls unsere T\u00e4tigkeit doch einmal im Ausland ausgef\u00fchrt wird, gilt das Deutsche Recht. Kaufvertr\u00e4ge bed\u00fcrfen keiner Schriftform.<\/p>\n<ul>\n<li>Nachdem Sie Ihr Obst auf das F\u00f6rderband der mobilen \u201eApfelquetsche\u201c gegeben haben, gilt dies automatisch als Auftrag. <\/li>\n<li>Der Auftrag muss entsprechend der produzierten Saftmenge beglichen werden.<\/li>\n<li>Es gelten die vor Ort angeschlagenen Preise.<\/li>\n<li>Die <a href=\"http:\/\/www.mobile-apfelquetsche.de\/preise\/\" title=\"Preise mobile Mosterei\">Preise<\/a> verstehen sich incl. der gesetzlichen Mehrwertsteuer.<\/li>\n<\/ul>\n<p>Je nach Reifegrad und Obstsorte quetschen wir eine Ausbeute von ungef\u00e4hr 70 %. Die Qualit\u00e4t und Haltbarkeit des Endproduktes Saft ist von der Qualit\u00e4t  des verwendeten Obstes abh\u00e4ngig.<\/p>\n<p>Da wir vor Ort keine Qualit\u00e4tskontrolle vornehmen k\u00f6nnen \u00fcbernehmen wir keinerlei Garantieanspr\u00fcche bez\u00fcglich der Haltbarkeit.<\/p>\n<p>Im Falle von technischen St\u00f6rungen, Defekten oder unabwendbaren Ereignissen besteht kein Rechtsanspruch.<br \/>\nNat\u00fcrlich versuchen wir eine f\u00fcr beide Parteien ertr\u00e4gliche L\u00f6sung zu finden.<\/p>\n<p>Bei l\u00e4ngeren Wartezeiten bauen wir auf gutes Wetter und innere Ruhe und freuen uns f\u00fcr Sie t\u00e4tig werden zu k\u00f6nnen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Wir werden vorrangig im deutschen Raum arbeiten, falls unsere T\u00e4tigkeit doch einmal im Ausland ausgef\u00fchrt wird, gilt das Deutsche Recht. Kaufvertr\u00e4ge bed\u00fcrfen keiner Schriftform. Nachdem Sie Ihr Obst auf das F\u00f6rderband der mobilen \u201eApfelquetsche\u201c gegeben &hellip; <a href=\"https:\/\/www.mobile-apfelquetsche.de\/idee-apfelquetsche\/agb\/\">Weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.mobile-apfelquetsche.de\/idee-apfelquetsche\/wp-json\/wp\/v2\/pages\/73"}],"collection":[{"href":"https:\/\/www.mobile-apfelquetsche.de\/idee-apfelquetsche\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.mobile-apfelquetsche.de\/idee-apfelquetsche\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.mobile-apfelquetsche.de\/idee-apfelquetsche\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mobile-apfelquetsche.de\/idee-apfelquetsche\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":12,"href":"https:\/\/www.mobile-apfelquetsche.de\/idee-apfelquetsche\/wp-json\/wp\/v2\/pages\/73\/revisions"}],"predecessor-version":[{"id":154,"href":"https:\/\/www.mobile-apfelquetsche.de\/idee-apfelquetsche\/wp-json\/wp\/v2\/pages\/73\/revisions\/154"}],"wp:attachment":[{"href":"https:\/\/www.mobile-apfelquetsche.de\/idee-apfelquetsche\/wp-json\/wp\/v2\/media?parent=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}